{"id":307,"count":27,"description":"Las bombas Nash son reconocidas por su innovaci\u00f3n y confiabilidad en la tecnolog\u00eda de bombas de vac\u00edo. Con un legado de excelencia ingenieril, las bombas Nash ofrecen soluciones eficientes para diversas aplicaciones industriales, asegurando un rendimiento \u00f3ptimo y durabilidad","link":"https:\/\/amed-us.com\/es\/manufacturer\/nash-es\/","name":"Fabricante Nash","slug":"nash-es","taxonomy":"product_manufacturer","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/product_manufacturer\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/product_manufacturer"}],"about":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_manufacturer"}],"wp:post_type":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/products?product_manufacturer=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}