{"id":264,"count":10,"description":"Las bombas Borger son conocidas por su dise\u00f1o robusto y su eficiente rendimiento en el manejo de fluidos abrasivos y viscosos. Con un enfoque en la durabilidad y la facilidad de mantenimiento, las bombas Borger destacan en condiciones de operaci\u00f3n dif\u00edciles.","link":"https:\/\/amed-us.com\/es\/manufacturer\/borger-es\/","name":"Fabricante Borger","slug":"borger-es","taxonomy":"product_manufacturer","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/product_manufacturer\/264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/product_manufacturer"}],"about":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_manufacturer"}],"wp:post_type":[{"href":"https:\/\/amed-us.com\/es\/wp-json\/wp\/v2\/products?product_manufacturer=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}